{"id":1114,"count":1,"description":"","link":"https:\/\/www.ilfioretralespine.it\/en\/tag\/onzuka-2\/","name":"onzuka","slug":"onzuka-2","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>onzuka Archivi - Il fiore tra le spine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ilfioretralespine.it\/en\/tag\/onzuka-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"onzuka Archivi - Il fiore tra le spine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ilfioretralespine.it\/en\/tag\/onzuka-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Il fiore tra le spine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.ilfioretralespine.it\\\/en\\\/tag\\\/onzuka-2\\\/\",\"url\":\"https:\\\/\\\/www.ilfioretralespine.it\\\/en\\\/tag\\\/onzuka-2\\\/\",\"name\":\"onzuka Archivi - Il fiore tra le spine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ilfioretralespine.it\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ilfioretralespine.it\\\/en\\\/tag\\\/onzuka-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ilfioretralespine.it\\\/en\\\/tag\\\/onzuka-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ilfioretralespine.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"onzuka\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ilfioretralespine.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ilfioretralespine.it\\\/en\\\/\",\"name\":\"Il fiore tra le spine\",\"description\":\"Due o tre cose che ho imparato su cactus e piante grasse\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ilfioretralespine.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ilfioretralespine.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ilfioretralespine.it\\\/en\\\/#organization\",\"name\":\"Il fiore tra le spine\",\"url\":\"https:\\\/\\\/www.ilfioretralespine.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ilfioretralespine.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ilfioretralespine.it\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Logo-x-browser-definitivo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ilfioretralespine.it\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Logo-x-browser-definitivo.jpg\",\"width\":508,\"height\":500,\"caption\":\"Il fiore tra le spine\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ilfioretralespine.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ilfioretralespine\",\"https:\\\/\\\/www.instagram.com\\\/il_fiore_tra_le_spine\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@il_fiore_tra_le_spine\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCuaHz-ay5W6mN_YJBSNdNZA?view_as=subscriber\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"onzuka Archivi - Il fiore tra le spine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ilfioretralespine.it\/en\/tag\/onzuka-2\/","og_locale":"en_US","og_type":"article","og_title":"onzuka Archivi - Il fiore tra le spine","og_url":"https:\/\/www.ilfioretralespine.it\/en\/tag\/onzuka-2\/","og_site_name":"Il fiore tra le spine","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.ilfioretralespine.it\/en\/tag\/onzuka-2\/","url":"https:\/\/www.ilfioretralespine.it\/en\/tag\/onzuka-2\/","name":"onzuka Archivi - Il fiore tra le spine","isPartOf":{"@id":"https:\/\/www.ilfioretralespine.it\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.ilfioretralespine.it\/en\/tag\/onzuka-2\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ilfioretralespine.it\/en\/tag\/onzuka-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ilfioretralespine.it\/en\/"},{"@type":"ListItem","position":2,"name":"onzuka"}]},{"@type":"WebSite","@id":"https:\/\/www.ilfioretralespine.it\/en\/#website","url":"https:\/\/www.ilfioretralespine.it\/en\/","name":"Il fiore tra le spine","description":"Due o tre cose che ho imparato su cactus e piante grasse","publisher":{"@id":"https:\/\/www.ilfioretralespine.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ilfioretralespine.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ilfioretralespine.it\/en\/#organization","name":"Il fiore tra le spine","url":"https:\/\/www.ilfioretralespine.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ilfioretralespine.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ilfioretralespine.it\/wp-content\/uploads\/2018\/03\/Logo-x-browser-definitivo.jpg","contentUrl":"https:\/\/www.ilfioretralespine.it\/wp-content\/uploads\/2018\/03\/Logo-x-browser-definitivo.jpg","width":508,"height":500,"caption":"Il fiore tra le spine"},"image":{"@id":"https:\/\/www.ilfioretralespine.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ilfioretralespine","https:\/\/www.instagram.com\/il_fiore_tra_le_spine\/","https:\/\/www.tiktok.com\/@il_fiore_tra_le_spine\/","https:\/\/www.youtube.com\/channel\/UCuaHz-ay5W6mN_YJBSNdNZA?view_as=subscriber"]}]}},"_links":{"self":[{"href":"https:\/\/www.ilfioretralespine.it\/en\/wp-json\/wp\/v2\/tags\/1114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ilfioretralespine.it\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.ilfioretralespine.it\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.ilfioretralespine.it\/en\/wp-json\/wp\/v2\/posts?tags=1114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}